{"id":33,"count":3,"description":"","link":"https:\/\/loop-of-light.com\/nb\/tag\/journal\/","name":"journal","slug":"journal","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>journal Archives - Loop of Light<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loop-of-light.com\/nb\/tag\/journal\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"journal Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loop-of-light.com\/nb\/tag\/journal\/\" \/>\n<meta property=\"og:site_name\" content=\"Loop of Light\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/loop-of-light.com\\\/tag\\\/journal\\\/\",\"url\":\"https:\\\/\\\/loop-of-light.com\\\/tag\\\/journal\\\/\",\"name\":\"journal Archives - Loop of Light\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loop-of-light.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loop-of-light.com\\\/tag\\\/journal\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loop-of-light.com\\\/tag\\\/journal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/loop-of-light.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"journal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loop-of-light.com\\\/#website\",\"url\":\"https:\\\/\\\/loop-of-light.com\\\/\",\"name\":\"Loop-of-light.com\",\"description\":\"Creativity with calm\",\"publisher\":{\"@id\":\"https:\\\/\\\/loop-of-light.com\\\/#\\\/schema\\\/person\\\/c0a33ff135d2d321a191176e6446ead9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loop-of-light.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/loop-of-light.com\\\/#\\\/schema\\\/person\\\/c0a33ff135d2d321a191176e6446ead9\",\"name\":\"Bente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/loop-of-light.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-1.webp?fit=512%2C512&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/loop-of-light.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-1.webp?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/loop-of-light.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-1.webp?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Bente\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/loop-of-light.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-1.webp?fit=512%2C512&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/loop-of-light.com\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61575882834639\",\"https:\\\/\\\/www.instagram.com\\\/skaperglede_med_hvilepuls\\\/\",\"https:\\\/\\\/no.pinterest.com\\\/Loopoflight\\\/?actingBusinessId=305893137098757733\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"journal Archives - Loop of Light","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loop-of-light.com\/nb\/tag\/journal\/","og_locale":"nb_NO","og_type":"article","og_title":"journal Archives","og_url":"https:\/\/loop-of-light.com\/nb\/tag\/journal\/","og_site_name":"Loop of Light","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/loop-of-light.com\/tag\/journal\/","url":"https:\/\/loop-of-light.com\/tag\/journal\/","name":"journal Archives - Loop of Light","isPartOf":{"@id":"https:\/\/loop-of-light.com\/#website"},"breadcrumb":{"@id":"https:\/\/loop-of-light.com\/tag\/journal\/#breadcrumb"},"inLanguage":"nb-NO"},{"@type":"BreadcrumbList","@id":"https:\/\/loop-of-light.com\/tag\/journal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/loop-of-light.com\/"},{"@type":"ListItem","position":2,"name":"journal"}]},{"@type":"WebSite","@id":"https:\/\/loop-of-light.com\/#website","url":"https:\/\/loop-of-light.com\/","name":"Loop-of-light.com","description":"Creativity with calm","publisher":{"@id":"https:\/\/loop-of-light.com\/#\/schema\/person\/c0a33ff135d2d321a191176e6446ead9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loop-of-light.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":["Person","Organization"],"@id":"https:\/\/loop-of-light.com\/#\/schema\/person\/c0a33ff135d2d321a191176e6446ead9","name":"Bente","image":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/i0.wp.com\/loop-of-light.com\/wp-content\/uploads\/2025\/06\/cropped-logo-1.webp?fit=512%2C512&ssl=1","url":"https:\/\/i0.wp.com\/loop-of-light.com\/wp-content\/uploads\/2025\/06\/cropped-logo-1.webp?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/loop-of-light.com\/wp-content\/uploads\/2025\/06\/cropped-logo-1.webp?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Bente"},"logo":{"@id":"https:\/\/i0.wp.com\/loop-of-light.com\/wp-content\/uploads\/2025\/06\/cropped-logo-1.webp?fit=512%2C512&ssl=1"},"sameAs":["http:\/\/loop-of-light.com","https:\/\/www.facebook.com\/profile.php?id=61575882834639","https:\/\/www.instagram.com\/skaperglede_med_hvilepuls\/","https:\/\/no.pinterest.com\/Loopoflight\/?actingBusinessId=305893137098757733"]}]}},"_links":{"self":[{"href":"https:\/\/loop-of-light.com\/nb\/wp-json\/wp\/v2\/tags\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loop-of-light.com\/nb\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/loop-of-light.com\/nb\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/loop-of-light.com\/nb\/wp-json\/wp\/v2\/posts?tags=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}